{"id":24913,"date":"2024-05-02T10:00:00","date_gmt":"2024-05-02T03:00:00","guid":{"rendered":"https:\/\/www.nxpo.or.th\/th\/?p=24913"},"modified":"2024-05-20T18:35:55","modified_gmt":"2024-05-20T11:35:55","slug":"%e0%b8%aa%e0%b8%ad%e0%b8%a7%e0%b8%8a-%e0%b9%80%e0%b8%9c%e0%b8%a2%e0%b8%9c%e0%b8%a5%e0%b8%81%e0%b8%b2%e0%b8%a3%e0%b8%94%e0%b8%b3%e0%b9%80%e0%b8%99%e0%b8%b4%e0%b8%99%e0%b8%87%e0%b8%b2%e0%b8%99-2","status":"publish","type":"post","link":"https:\/\/www.nxpo.or.th\/th\/24913\/","title":{"rendered":"\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07 \u0e2d\u0e27. \u0e42\u0e14\u0e22 \u0e2a\u0e2d\u0e27\u0e0a. \u0e40\u0e1c\u0e22\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19 2 \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a \u0e2b\u0e19\u0e38\u0e19\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01 Future Food \u0e2b\u0e25\u0e31\u0e07\u0e2a\u0e16\u0e34\u0e15\u0e34\u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e1e\u0e1a\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e07 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e41\u0e19\u0e27\u0e42\u0e19\u0e49\u0e21\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">(1 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567) \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e38\u0e20\u0e21\u0e32\u0e2a \u0e2d\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01\u0e23\u0e30\u0e17\u0e23\u0e27\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27.) \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e04\u0e13\u0e30\u0e01\u0e23\u0e23\u0e21\u0e01\u0e32\u0e23\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e2a\u0e20\u0e32\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e0a\u0e32\u0e15\u0e34 (\u0e01\u0e2d\u0e27\u0e0a.) \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 3\/2567 \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e0a\u0e31\u0e49\u0e19 3 \u0e2d\u0e32\u0e04\u0e32\u0e23 \u0e2a\u0e27\u0e17\u0e0a. (\u0e42\u0e22\u0e18\u0e35) \u0e42\u0e14\u0e22\u0e21\u0e35\u0e01\u0e32\u0e23\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e14\u0e4d\u0e32\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07 \u0e2a\u0e2d\u0e27\u0e0a. \u0e44\u0e15\u0e23\u0e21\u0e32\u0e2a\u0e17\u0e35\u0e48 1-2 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 2567<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-1024x682.jpg\" alt=\"\" class=\"wp-image-24914\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-1024x682.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-1536x1023.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/20240501_035606481_iOS-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02-1024x683.jpg\" alt=\"\" class=\"wp-image-24918\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02-1536x1025.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e23\u0e2d\u0e27._02.jpg 1646w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22-1024x683.jpg\" alt=\"\" class=\"wp-image-24919\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e44\u0e2d\u0e40\u0e14\u0e35\u0e22.jpg 1226w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e2d\u0e27\u0e0a. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07 \u0e2a\u0e2d\u0e27\u0e0a. \u0e43\u0e19\u0e1b\u0e35 2567 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 5 \u0e14\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 1. \u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e43\u0e2b\u0e49\u0e1e\u0e49\u0e19\u0e08\u0e32\u0e01\u0e01\u0e31\u0e1a\u0e14\u0e31\u0e01\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e1b\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e08\u0e33\u0e19\u0e27\u0e19\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 2. Social Mobility \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01\u0e41\u0e25\u0e30\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2b\u0e25\u0e37\u0e48\u0e2d\u0e21\u0e25\u0e49\u0e33\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21 (\u0e2d\u0e27\u0e27\u0e19.) 3. \u0e25\u0e14\u0e01\u0e4a\u0e32\u0e0b\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e01\u0e23\u0e30\u0e08\u0e01 10 \u0e25\u0e49\u0e32\u0e19\u0e15\u0e31\u0e19 \u0e04\u0e32\u0e23\u0e4c\u0e1a\u0e2d\u0e19\u0e44\u0e14\u0e2d\u0e2d\u0e01\u0e44\u0e0b\u0e14\u0e4c\u0e40\u0e17\u0e35\u0e22\u0e1a\u0e40\u0e17\u0e48\u0e32 4. \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e2a\u0e31\u0e14\u0e2a\u0e48\u0e27\u0e19\u0e41\u0e23\u0e07\u0e07\u0e32\u0e19\u0e17\u0e31\u0e01\u0e29\u0e30\u0e2a\u0e39\u0e07 \u0e40\u0e1b\u0e47\u0e19 25% \u0e41\u0e25\u0e30 5. \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e1a\u0e1a \u0e2d\u0e27\u0e27\u0e19.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c_01-1024x683.jpg\" alt=\"\" class=\"wp-image-24915\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c_01-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c_01-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c_01-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c-\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e27\u0e07\u0e04\u0e4c_01.jpg 1476w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e1c\u0e39\u0e49\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e01\u0e32\u0e23 \u0e40\u0e02\u0e49\u0e32\u0e2a\u0e39\u0e48\u0e15\u0e25\u0e32\u0e14\u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e41\u0e25\u0e30\u0e15\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e2d\u0e35\u0e01\u0e17\u0e31\u0e49\u0e07\u0e22\u0e31\u0e07\u0e44\u0e14\u0e49\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 (Future Industry) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e10\u0e32\u0e19\u0e23\u0e32\u0e01 \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19\u0e40\u0e23\u0e32\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e19\u0e34\u0e40\u0e27\u0e28\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e25\u0e44\u0e01\u0e2b\u0e19\u0e38\u0e19 GNH Net Zero \u0e15\u0e25\u0e2d\u0e14\u0e08\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e1e\u0e25\u0e15\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e01\u0e33\u0e25\u0e31\u0e07\u0e04\u0e19\u0e2a\u0e21\u0e23\u0e23\u0e16\u0e19\u0e30\u0e2a\u0e39\u0e07 \u0e2a\u0e23\u0e49\u0e32\u0e07 University transformation \u0e40\u0e1e\u0e34\u0e48\u0e21\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e38\u0e14\u0e21\u0e28\u0e36\u0e01\u0e29\u0e32 \u0e27\u0e34\u0e17\u0e22\u0e32\u0e28\u0e32\u0e2a\u0e15\u0e23\u0e4c \u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e19\u0e27\u0e31\u0e15\u0e01\u0e23\u0e23\u0e21\u201d \u0e14\u0e23.\u0e01\u0e34\u0e15\u0e34\u0e1e\u0e07\u0e04\u0e4c \u0e01\u0e25\u0e48\u0e32\u0e27 <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-1024x683.jpg\" alt=\"\" class=\"wp-image-24916\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-1536x1024.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/IMG_2040-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e19\u0e43\u0e08\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e34\u0e40\u0e28\u0e29 \u0e04\u0e37\u0e2d\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15 (Future Food) \u0e42\u0e14\u0e22 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e2d\u0e27\u0e0a. \u0e01\u0e25\u0e48\u0e32\u0e27\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e40\u0e1b\u0e47\u0e19 Future Food Industry \u0e19\u0e31\u0e49\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e17\u0e33\u0e44\u0e14\u0e49 \u0e0b\u0e36\u0e48\u0e07 \u0e2a\u0e2d\u0e27\u0e0a. \u0e44\u0e14\u0e49\u0e27\u0e32\u0e07\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e44\u0e27\u0e49\u0e04\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1c\u0e25\u0e34\u0e15\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e2b\u0e48\u0e07\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e15\u0e49\u0e2d\u0e07\u0e25\u0e14\u0e01\u0e32\u0e23\u0e1b\u0e25\u0e48\u0e2d\u0e22 GHGs \u0e0b\u0e36\u0e48\u0e07\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e08\u0e30\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e41\u0e25\u0e49\u0e27 \u0e22\u0e31\u0e07\u0e01\u0e23\u0e30\u0e08\u0e32\u0e22\u0e23\u0e32\u0e22\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14\u0e2b\u0e48\u0e27\u0e07\u0e42\u0e0b\u0e48\u0e2d\u0e38\u0e1b\u0e17\u0e32\u0e19 \u0e02\u0e13\u0e30\u0e40\u0e14\u0e35\u0e22\u0e27\u0e01\u0e31\u0e19 \u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e0a\u0e31\u0e49\u0e19\u0e19\u0e33 \u0e40\u0e0a\u0e48\u0e19 \u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32 \u0e2a\u0e34\u0e07\u0e04\u0e42\u0e1b\u0e23\u0e4c \u0e2d\u0e34\u0e2a\u0e23\u0e32\u0e40\u0e2d\u0e25 \u0e2d\u0e34\u0e19\u0e40\u0e14\u0e35\u0e22 \u0e40\u0e01\u0e32\u0e2b\u0e25\u0e35\u0e43\u0e15\u0e49 \u0e41\u0e25\u0e30\u0e2d\u0e2d\u0e2a\u0e40\u0e15\u0e23\u0e40\u0e25\u0e35\u0e22 \u0e2d\u0e2d\u0e01\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a Novel Food \u0e41\u0e25\u0e49\u0e27 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22\u0e40\u0e23\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2a\u0e48\u0e07\u0e2d\u0e2d\u0e01\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e2d\u0e31\u0e19\u0e14\u0e31\u0e1a\u0e17\u0e35\u0e48 12 \u0e02\u0e2d\u0e07\u0e42\u0e25\u0e01 \u0e42\u0e14\u0e22\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e1b\u0e35 2566 \u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32\u0e15\u0e25\u0e32\u0e14\u0e17\u0e31\u0e49\u0e07\u0e2a\u0e34\u0e49\u0e19 15 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e1a\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19 Future Food 143,000 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e42\u0e14\u0e22\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 Future Food \u0e17\u0e31\u0e48\u0e27\u0e42\u0e25\u0e01\u0e21\u0e35\u0e21\u0e39\u0e25\u0e04\u0e48\u0e32 14 \u0e25\u0e49\u0e32\u0e19\u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e41\u0e25\u0e30\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e2a\u0e39\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21 Functional Food, Functional Ingredient \u0e41\u0e25\u0e30 Alt protein<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24921\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-1024x683.jpg\" alt=\"\" class=\"wp-image-24921\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-1536x1024.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e04\u0e38\u0e13\u0e23\u0e15\u0e34\u0e21\u0e32-\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e18\u0e23\u0e23\u0e21\u0e32\u0e20\u0e34\u0e21\u0e38\u0e02-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24922\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-1024x683.jpg\" alt=\"\" class=\"wp-image-24922\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-1536x1024.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e2a\u0e34\u0e23\u0e34\u0e1e\u0e23-2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" data-id=\"24920\" src=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--1024x683.jpg\" alt=\"\" class=\"wp-image-24920\" srcset=\"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--1024x683.jpg 1024w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--300x200.jpg 300w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--768x512.jpg 768w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--1536x1024.jpg 1536w, https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/\u0e14\u0e23.\u0e01\u0e34\u0e15\u0e15\u0e34-\u0e2a\u0e31\u0e08\u0e08\u0e32\u0e27\u0e31\u0e12\u0e19\u0e32--2048x1365.jpg 2048w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>(1 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2567) \u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e28\u0e38\u0e20\u0e21\u0e32\u0e2a \u0e2d\u0e34\u0e28\u0e23\u0e20\u0e31\u0e01\u0e14\u0e35 \u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e27\u0e48\u0e32\u0e01\u0e32\u0e23\u0e01 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":24923,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[1],"tags":[1320,1322],"class_list":["post-24913","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-future-food","tag-1322"],"featured_image_src":"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/cover-Website-2-\u0e1e.\u0e04.67.jpg","author_info":{"display_name":"admin","author_link":"https:\/\/www.nxpo.or.th\/th\/author\/adminsti\/"},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/www.nxpo.or.th\/th\/wp-content\/uploads\/2024\/05\/cover-Website-2-\u0e1e.\u0e04.67.jpg","_links":{"self":[{"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/posts\/24913","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/comments?post=24913"}],"version-history":[{"count":2,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/posts\/24913\/revisions"}],"predecessor-version":[{"id":25188,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/posts\/24913\/revisions\/25188"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/media\/24923"}],"wp:attachment":[{"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/media?parent=24913"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/categories?post=24913"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.nxpo.or.th\/th\/wp-json\/wp\/v2\/tags?post=24913"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}